{"id":127,"count":126,"description":"","link":"https:\/\/www.archimetric.com\/cn\/category\/unified-modeling-language\/","name":"Unified Modeling Language","slug":"unified-modeling-language","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unified Modeling Language Archives - ArchiMetric Simplified Chinese<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.archimetric.com\/cn\/category\/unified-modeling-language\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unified Modeling Language Archives - ArchiMetric Simplified Chinese\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.archimetric.com\/cn\/category\/unified-modeling-language\/\" \/>\n<meta property=\"og:site_name\" content=\"ArchiMetric Simplified Chinese\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.archimetric.com\/cn\/category\/unified-modeling-language\/\",\"url\":\"https:\/\/www.archimetric.com\/cn\/category\/unified-modeling-language\/\",\"name\":\"Unified Modeling Language Archives - ArchiMetric Simplified Chinese\",\"isPartOf\":{\"@id\":\"https:\/\/www.archimetric.com\/cn\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.archimetric.com\/cn\/category\/unified-modeling-language\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.archimetric.com\/cn\/category\/unified-modeling-language\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.archimetric.com\/cn\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unified Modeling Language\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.archimetric.com\/cn\/#website\",\"url\":\"https:\/\/www.archimetric.com\/cn\/\",\"name\":\"ArchiMetric Simplified Chinese\",\"description\":\"EA, Dev Ops, Scrum, Agile and More\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.archimetric.com\/cn\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unified Modeling Language Archives - ArchiMetric Simplified Chinese","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.archimetric.com\/cn\/category\/unified-modeling-language\/","og_locale":"zh_CN","og_type":"article","og_title":"Unified Modeling Language Archives - ArchiMetric Simplified Chinese","og_url":"https:\/\/www.archimetric.com\/cn\/category\/unified-modeling-language\/","og_site_name":"ArchiMetric Simplified Chinese","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.archimetric.com\/cn\/category\/unified-modeling-language\/","url":"https:\/\/www.archimetric.com\/cn\/category\/unified-modeling-language\/","name":"Unified Modeling Language Archives - ArchiMetric Simplified Chinese","isPartOf":{"@id":"https:\/\/www.archimetric.com\/cn\/#website"},"breadcrumb":{"@id":"https:\/\/www.archimetric.com\/cn\/category\/unified-modeling-language\/#breadcrumb"},"inLanguage":"zh-Hans"},{"@type":"BreadcrumbList","@id":"https:\/\/www.archimetric.com\/cn\/category\/unified-modeling-language\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.archimetric.com\/cn\/"},{"@type":"ListItem","position":2,"name":"Unified Modeling Language"}]},{"@type":"WebSite","@id":"https:\/\/www.archimetric.com\/cn\/#website","url":"https:\/\/www.archimetric.com\/cn\/","name":"ArchiMetric Simplified Chinese","description":"EA, Dev Ops, Scrum, Agile and More","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.archimetric.com\/cn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"}]}},"_links":{"self":[{"href":"https:\/\/www.archimetric.com\/cn\/wp-json\/wp\/v2\/categories\/127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archimetric.com\/cn\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.archimetric.com\/cn\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.archimetric.com\/cn\/wp-json\/wp\/v2\/posts?categories=127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}